{"id":14191,"date":"2022-02-11T15:59:59","date_gmt":"2022-02-11T12:59:59","guid":{"rendered":"https:\/\/platinon.gr\/?page_id=14191"},"modified":"2022-02-11T15:59:59","modified_gmt":"2022-02-11T12:59:59","slug":"cart-2","status":"publish","type":"page","link":"https:\/\/platinon.gr\/en\/cart-2\/","title":{"rendered":"Cart"},"content":{"rendered":"\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"class_list":["post-14191","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cart - Platinon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/platinon.gr\/en\/cart-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cart - Platinon\" \/>\n<meta property=\"og:url\" content=\"https:\/\/platinon.gr\/en\/cart-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Platinon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PlatinonJewellery\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/platinon.gr\/wp-content\/uploads\/2022\/02\/platinon-logo-01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/platinon.gr\\\/en\\\/cart-2\\\/\",\"url\":\"https:\\\/\\\/platinon.gr\\\/en\\\/cart-2\\\/\",\"name\":\"Cart - Platinon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/platinon.gr\\\/#website\"},\"datePublished\":\"2022-02-11T12:59:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/platinon.gr\\\/en\\\/cart-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/platinon.gr\\\/en\\\/cart-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/platinon.gr\\\/en\\\/cart-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/platinon.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cart\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/platinon.gr\\\/#website\",\"url\":\"https:\\\/\\\/platinon.gr\\\/\",\"name\":\"Platinon\",\"description\":\"\u039b\u03b9\u03b1\u03bd\u03b9\u03ba\u03cc \u0395\u03bc\u03c0\u03cc\u03c1\u03b9\u03bf \u039a\u03bf\u03c3\u03bc\u03b7\u03bc\u03b1\u03c4\u03bf\u03c0\u03bf\u03b9\u03af\u03b1\u03c2\",\"publisher\":{\"@id\":\"https:\\\/\\\/platinon.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/platinon.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/platinon.gr\\\/#organization\",\"name\":\"Platinon\",\"url\":\"https:\\\/\\\/platinon.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/platinon.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/platinon.gr\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/platinon-logo-01.png\",\"contentUrl\":\"https:\\\/\\\/platinon.gr\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/platinon-logo-01.png\",\"width\":1200,\"height\":675,\"caption\":\"Platinon\"},\"image\":{\"@id\":\"https:\\\/\\\/platinon.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PlatinonJewellery\\\/\",\"https:\\\/\\\/www.instagram.com\\\/platinon_jewellery\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cart - Platinon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/platinon.gr\/en\/cart-2\/","og_locale":"en_US","og_type":"article","og_title":"Cart - Platinon","og_url":"https:\/\/platinon.gr\/en\/cart-2\/","og_site_name":"Platinon","article_publisher":"https:\/\/www.facebook.com\/PlatinonJewellery\/","og_image":[{"width":1200,"height":675,"url":"https:\/\/platinon.gr\/wp-content\/uploads\/2022\/02\/platinon-logo-01.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/platinon.gr\/en\/cart-2\/","url":"https:\/\/platinon.gr\/en\/cart-2\/","name":"Cart - Platinon","isPartOf":{"@id":"https:\/\/platinon.gr\/#website"},"datePublished":"2022-02-11T12:59:59+00:00","breadcrumb":{"@id":"https:\/\/platinon.gr\/en\/cart-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/platinon.gr\/en\/cart-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/platinon.gr\/en\/cart-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/platinon.gr\/en\/"},{"@type":"ListItem","position":2,"name":"Cart"}]},{"@type":"WebSite","@id":"https:\/\/platinon.gr\/#website","url":"https:\/\/platinon.gr\/","name":"Platinon","description":"\u039b\u03b9\u03b1\u03bd\u03b9\u03ba\u03cc \u0395\u03bc\u03c0\u03cc\u03c1\u03b9\u03bf \u039a\u03bf\u03c3\u03bc\u03b7\u03bc\u03b1\u03c4\u03bf\u03c0\u03bf\u03b9\u03af\u03b1\u03c2","publisher":{"@id":"https:\/\/platinon.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/platinon.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/platinon.gr\/#organization","name":"Platinon","url":"https:\/\/platinon.gr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/platinon.gr\/#\/schema\/logo\/image\/","url":"https:\/\/platinon.gr\/wp-content\/uploads\/2022\/02\/platinon-logo-01.png","contentUrl":"https:\/\/platinon.gr\/wp-content\/uploads\/2022\/02\/platinon-logo-01.png","width":1200,"height":675,"caption":"Platinon"},"image":{"@id":"https:\/\/platinon.gr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PlatinonJewellery\/","https:\/\/www.instagram.com\/platinon_jewellery\/"]}]}},"_links":{"self":[{"href":"https:\/\/platinon.gr\/en\/wp-json\/wp\/v2\/pages\/14191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/platinon.gr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/platinon.gr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/platinon.gr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/platinon.gr\/en\/wp-json\/wp\/v2\/comments?post=14191"}],"version-history":[{"count":0,"href":"https:\/\/platinon.gr\/en\/wp-json\/wp\/v2\/pages\/14191\/revisions"}],"wp:attachment":[{"href":"https:\/\/platinon.gr\/en\/wp-json\/wp\/v2\/media?parent=14191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}